{"id":417,"date":"2024-10-18T16:00:20","date_gmt":"2024-10-18T13:00:20","guid":{"rendered":"https:\/\/teddyway.fr\/?post_type=product&#038;p=417"},"modified":"2026-09-02T00:00:42","modified_gmt":"2026-09-02T00:00:42","slug":"teddyway-bobo-large-teddy-bear-plush-toy-100cm-grey","status":"publish","type":"product","link":"https:\/\/teddyway.fr\/en\/produits\/teddyway-bobo-grand-ourson-en-peluche-jouet-en-peluche-100-cm-gris\/","title":{"rendered":"Teddyway Bobo Large Teddy Bear Giant Plush Toy, 100cm, Grey"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Product information:<\/p>\n<ul>\n<li>The exclusive and universal surprise for your partner, your child or a loved one.<\/li>\n<li>Multiple uses: Plush toys can replace upholstered furniture, create comfort as a decorative detail for the home, or simply delight family members during games and leisure time.<\/li>\n<li>They are made with love and meet all European Union safety standards and requirements.<\/li>\n<li>The plush toys are filled with silicone ball fibers, which not only retain their shape, but also have anti-allergic properties.<\/li>\n<\/ul>\n<p>*Toys should never be left unattended with children under three years old.<\/p>\n<p>*Das Aussehen und die Farbe des Produkts k\u00f6nnen von den im Online-Shop bereitgestellten Fotos etwas abweichen.<\/p>","protected":false},"featured_media":1742,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[22],"product_cat":[17,18,19,20],"product_tag":[],"class_list":["post-417","product","type-product","status-publish","has-post-thumbnail","product_brand-teddyway","product_cat-grands-jouets-en-peluche","product_cat-oursons","product_cat-jouets","product_cat-jouets-en-peluche","desktop-align-center","tablet-align-center","mobile-align-center","ast-product-gallery-layout-horizontal-slider","ast-magnify-disabled","ast-product-tabs-layout-horizontal","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Teddyway Bobo Grand Ourson En Peluche Ours G\u00e9ant, Jouet En Peluche, 100 Cm, Gris - Teddyway<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teddyway.fr\/en\/products\/teddyway-bobo-large-teddy-bear-plush-toy-100cm-grey\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teddyway Bobo Grand Ourson En Peluche Ours G\u00e9ant, Jouet En Peluche, 100 Cm, Gris - Teddyway\" \/>\n<meta property=\"og:description\" content=\"Informations sur le produit:   La surprise exclusive et universelle \u00e0 votre moiti\u00e9, votre enfant ou \u00e0 un proche.  L\u2019utilisation multiple: les jouets en peluche peuvent remplacer les meubles rembourr\u00e9s, cr\u00e9er du confort comme un d\u00e9tail d\u00e9co pour la maison ou simplement ravir les membres de la famille lors de jeux et de loisirs.  Ils sont faits avec amour et r\u00e9pondant \u00e0 toutes les normes et exigences de s\u00e9curit\u00e9 de l\u2019Union europ\u00e9enne.  Les jouets en peluche sont remplis de fibres boules silicon\u00e9es, qui non seulement conservent leur forme, et pr\u00e9sentent \u00e9galement des caract\u00e9ristiques anti-allergiques.  *Les jouets ne sont jamais laiss\u00e9s sans surveillance avec des enfants de moins de trois ans.  *Das Aussehen und die Farbe des Produkts k\u00f6nnen von den im Online-Shop bereitgestellten Fotos etwas abweichen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teddyway.fr\/en\/products\/teddyway-bobo-large-teddy-bear-plush-toy-100cm-grey\/\" \/>\n<meta property=\"og:site_name\" content=\"Teddyway\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TeddyWayHome\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T00:00:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/teddyway.fr\/wp-content\/uploads\/2024\/10\/grey-giant-teddy-bear-100-cm-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TeddyWayHome\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/teddyway.fr\\\/produits\\\/teddyway-bobo-grand-ourson-en-peluche-jouet-en-peluche-100-cm-gris\\\/\",\"url\":\"https:\\\/\\\/teddyway.fr\\\/produits\\\/teddyway-bobo-grand-ourson-en-peluche-jouet-en-peluche-100-cm-gris\\\/\",\"name\":\"Teddyway Bobo Grand Ourson En Peluche Ours G\u00e9ant, Jouet En Peluche, 100 Cm, Gris - Teddyway\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/teddyway.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/teddyway.fr\\\/produits\\\/teddyway-bobo-grand-ourson-en-peluche-jouet-en-peluche-100-cm-gris\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/teddyway.fr\\\/produits\\\/teddyway-bobo-grand-ourson-en-peluche-jouet-en-peluche-100-cm-gris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/teddyway.fr\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/grey-giant-teddy-bear-100-cm-1.webp\",\"datePublished\":\"2024-10-18T13:00:20+00:00\",\"dateModified\":\"2026-09-02T00:00:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/teddyway.fr\\\/produits\\\/teddyway-bobo-grand-ourson-en-peluche-jouet-en-peluche-100-cm-gris\\\/#breadcrumb\"},\"inLanguage\":\"en-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/teddyway.fr\\\/produits\\\/teddyway-bobo-grand-ourson-en-peluche-jouet-en-peluche-100-cm-gris\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-FR\",\"@id\":\"https:\\\/\\\/teddyway.fr\\\/produits\\\/teddyway-bobo-grand-ourson-en-peluche-jouet-en-peluche-100-cm-gris\\\/#primaryimage\",\"url\":\"https:\\\/\\\/teddyway.fr\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/grey-giant-teddy-bear-100-cm-1.webp\",\"contentUrl\":\"https:\\\/\\\/teddyway.fr\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/grey-giant-teddy-bear-100-cm-1.webp\",\"width\":1000,\"height\":1000,\"caption\":\"Teddyway Bobo Grand Ourson En Peluche Ours G\u00e9ant, Jouet En Peluche, 100 Cm, Marron Clair - Teddyway\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/teddyway.fr\\\/produits\\\/teddyway-bobo-grand-ourson-en-peluche-jouet-en-peluche-100-cm-gris\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/teddyway.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/teddyway.fr\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jouets\",\"item\":\"https:\\\/\\\/teddyway.fr\\\/categories\\\/jouets\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Jouets en peluche\",\"item\":\"https:\\\/\\\/teddyway.fr\\\/categories\\\/jouets\\\/jouets-en-peluche\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Grands jouets en peluche\",\"item\":\"https:\\\/\\\/teddyway.fr\\\/categories\\\/jouets\\\/jouets-en-peluche\\\/grands-jouets-en-peluche\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Grands oursons en peluche\",\"item\":\"https:\\\/\\\/teddyway.fr\\\/categories\\\/jouets\\\/jouets-en-peluche\\\/grands-jouets-en-peluche\\\/oursons\\\/\"},{\"@type\":\"ListItem\",\"position\":7,\"name\":\"Teddyway Bobo Grand Ourson En Peluche Ours G\u00e9ant, Jouet En Peluche, 100 Cm, Gris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/teddyway.fr\\\/#website\",\"url\":\"https:\\\/\\\/teddyway.fr\\\/\",\"name\":\"Teddyway\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/teddyway.fr\\\/#organization\"},\"alternateName\":\"Teddyway\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/teddyway.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/teddyway.fr\\\/#organization\",\"name\":\"Teddyway\",\"url\":\"https:\\\/\\\/teddyway.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-FR\",\"@id\":\"https:\\\/\\\/teddyway.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/teddyway.fr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/teddyway-logo-web-sn.svg\",\"contentUrl\":\"https:\\\/\\\/teddyway.fr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/teddyway-logo-web-sn.svg\",\"caption\":\"Teddyway\"},\"image\":{\"@id\":\"https:\\\/\\\/teddyway.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TeddyWayHome\\\/\",\"https:\\\/\\\/x.com\\\/TeddyWayHome\",\"https:\\\/\\\/www.instagram.com\\\/teddyway\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/teddyway\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Teddyway\\\/videos\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Teddyway Bobo Large Teddy Bear, Giant Plush Toy, 100 cm, Grey - Teddyway","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teddyway.fr\/en\/products\/teddyway-bobo-large-teddy-bear-plush-toy-100cm-grey\/","og_locale":"en_US","og_type":"article","og_title":"Teddyway Bobo Grand Ourson En Peluche Ours G\u00e9ant, Jouet En Peluche, 100 Cm, Gris - Teddyway","og_description":"Informations sur le produit:   La surprise exclusive et universelle \u00e0 votre moiti\u00e9, votre enfant ou \u00e0 un proche.  L\u2019utilisation multiple: les jouets en peluche peuvent remplacer les meubles rembourr\u00e9s, cr\u00e9er du confort comme un d\u00e9tail d\u00e9co pour la maison ou simplement ravir les membres de la famille lors de jeux et de loisirs.  Ils sont faits avec amour et r\u00e9pondant \u00e0 toutes les normes et exigences de s\u00e9curit\u00e9 de l\u2019Union europ\u00e9enne.  Les jouets en peluche sont remplis de fibres boules silicon\u00e9es, qui non seulement conservent leur forme, et pr\u00e9sentent \u00e9galement des caract\u00e9ristiques anti-allergiques.  *Les jouets ne sont jamais laiss\u00e9s sans surveillance avec des enfants de moins de trois ans.  *Das Aussehen und die Farbe des Produkts k\u00f6nnen von den im Online-Shop bereitgestellten Fotos etwas abweichen.","og_url":"https:\/\/teddyway.fr\/en\/products\/teddyway-bobo-large-teddy-bear-plush-toy-100cm-grey\/","og_site_name":"Teddyway","article_publisher":"https:\/\/www.facebook.com\/TeddyWayHome\/","article_modified_time":"2026-09-02T00:00:42+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/teddyway.fr\/wp-content\/uploads\/2024\/10\/grey-giant-teddy-bear-100-cm-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@TeddyWayHome","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/teddyway.fr\/produits\/teddyway-bobo-grand-ourson-en-peluche-jouet-en-peluche-100-cm-gris\/","url":"https:\/\/teddyway.fr\/produits\/teddyway-bobo-grand-ourson-en-peluche-jouet-en-peluche-100-cm-gris\/","name":"Teddyway Bobo Large Teddy Bear, Giant Plush Toy, 100 cm, Grey - Teddyway","isPartOf":{"@id":"https:\/\/teddyway.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/teddyway.fr\/produits\/teddyway-bobo-grand-ourson-en-peluche-jouet-en-peluche-100-cm-gris\/#primaryimage"},"image":{"@id":"https:\/\/teddyway.fr\/produits\/teddyway-bobo-grand-ourson-en-peluche-jouet-en-peluche-100-cm-gris\/#primaryimage"},"thumbnailUrl":"https:\/\/teddyway.fr\/wp-content\/uploads\/2024\/10\/grey-giant-teddy-bear-100-cm-1.webp","datePublished":"2024-10-18T13:00:20+00:00","dateModified":"2026-09-02T00:00:42+00:00","breadcrumb":{"@id":"https:\/\/teddyway.fr\/produits\/teddyway-bobo-grand-ourson-en-peluche-jouet-en-peluche-100-cm-gris\/#breadcrumb"},"inLanguage":"en-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/teddyway.fr\/produits\/teddyway-bobo-grand-ourson-en-peluche-jouet-en-peluche-100-cm-gris\/"]}]},{"@type":"ImageObject","inLanguage":"en-FR","@id":"https:\/\/teddyway.fr\/produits\/teddyway-bobo-grand-ourson-en-peluche-jouet-en-peluche-100-cm-gris\/#primaryimage","url":"https:\/\/teddyway.fr\/wp-content\/uploads\/2024\/10\/grey-giant-teddy-bear-100-cm-1.webp","contentUrl":"https:\/\/teddyway.fr\/wp-content\/uploads\/2024\/10\/grey-giant-teddy-bear-100-cm-1.webp","width":1000,"height":1000,"caption":"Teddyway Bobo Grand Ourson En Peluche Ours G\u00e9ant, Jouet En Peluche, 100 Cm, Marron Clair - Teddyway"},{"@type":"BreadcrumbList","@id":"https:\/\/teddyway.fr\/produits\/teddyway-bobo-grand-ourson-en-peluche-jouet-en-peluche-100-cm-gris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/teddyway.fr\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/teddyway.fr\/produits\/"},{"@type":"ListItem","position":3,"name":"Jouets","item":"https:\/\/teddyway.fr\/categories\/jouets\/"},{"@type":"ListItem","position":4,"name":"Jouets en peluche","item":"https:\/\/teddyway.fr\/categories\/jouets\/jouets-en-peluche\/"},{"@type":"ListItem","position":5,"name":"Grands jouets en peluche","item":"https:\/\/teddyway.fr\/categories\/jouets\/jouets-en-peluche\/grands-jouets-en-peluche\/"},{"@type":"ListItem","position":6,"name":"Grands oursons en peluche","item":"https:\/\/teddyway.fr\/categories\/jouets\/jouets-en-peluche\/grands-jouets-en-peluche\/oursons\/"},{"@type":"ListItem","position":7,"name":"Teddyway Bobo Grand Ourson En Peluche Ours G\u00e9ant, Jouet En Peluche, 100 Cm, Gris"}]},{"@type":"WebSite","@id":"https:\/\/teddyway.fr\/#website","url":"https:\/\/teddyway.fr\/","name":"Teddyway","description":"","publisher":{"@id":"https:\/\/teddyway.fr\/#organization"},"alternateName":"Teddyway","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teddyway.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-FR"},{"@type":"Organization","@id":"https:\/\/teddyway.fr\/#organization","name":"Teddyway","url":"https:\/\/teddyway.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-FR","@id":"https:\/\/teddyway.fr\/#\/schema\/logo\/image\/","url":"https:\/\/teddyway.fr\/wp-content\/uploads\/2026\/03\/teddyway-logo-web-sn.svg","contentUrl":"https:\/\/teddyway.fr\/wp-content\/uploads\/2026\/03\/teddyway-logo-web-sn.svg","caption":"Teddyway"},"image":{"@id":"https:\/\/teddyway.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TeddyWayHome\/","https:\/\/x.com\/TeddyWayHome","https:\/\/www.instagram.com\/teddyway\/","https:\/\/www.pinterest.com\/teddyway\/","https:\/\/www.youtube.com\/c\/Teddyway\/videos"]}]}},"_links":{"self":[{"href":"https:\/\/teddyway.fr\/en\/wp-json\/wp\/v2\/product\/417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teddyway.fr\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/teddyway.fr\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teddyway.fr\/en\/wp-json\/wp\/v2\/media\/1742"}],"wp:attachment":[{"href":"https:\/\/teddyway.fr\/en\/wp-json\/wp\/v2\/media?parent=417"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/teddyway.fr\/en\/wp-json\/wp\/v2\/product_brand?post=417"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/teddyway.fr\/en\/wp-json\/wp\/v2\/product_cat?post=417"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/teddyway.fr\/en\/wp-json\/wp\/v2\/product_tag?post=417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}